{"id":1959,"date":"2025-09-04T18:05:09","date_gmt":"2025-09-04T16:05:09","guid":{"rendered":"https:\/\/ruedaloca-devel.italix.org\/?page_id=1959"},"modified":"2025-09-04T19:44:47","modified_gmt":"2025-09-04T17:44:47","slug":"die-kubanische-sose","status":"publish","type":"page","link":"https:\/\/www.ruedaloca.it\/de\/die-kubanische-sose\/","title":{"rendered":"Kubanische Salsa"},"content":{"rendered":"<style>\n .margin-top-p1 { margin-top: 20px; }\n<\/style>\n<p>\u00dcber Ort und Entstehungszeit gibt es keinen Zweifel: Der Salsa entstand Anfang des 20. Jahrhunderts in Kuba. Er leitet sich vom Son ab, \u00fcbernimmt jedoch wichtige Elemente aus anderen T\u00e4nzen wie Bolero, Merengue, Guaracha, Conga, Cumbia und Rumba. Im Vergleich zum Son ist das Tempo schneller, wobei die Funktion als Balztanz erhalten bleibt.<\/p>\n<p>Der synkopierte Rhythmus ist von Anfang an vorhanden; im Laufe der Jahre hat sich sein Tempo jedoch beschleunigt, und es wurden Dutzende von Figuren aus anderen T\u00e4nzen integriert. Neben den \u00fcblichen Perkussionsinstrumenten, die auch bei anderen karibischen T\u00e4nzen zum Einsatz kommen, sind in j\u00fcngster Zeit moderne Instrumente wie E-Gitarren, Schlagzeuge und Klaviere hinzugekommen.<\/p>\n<p class=\"margin-top-p1\">&nbsp;<\/p>\n<p>Der kubanische Salsa ist also ein historisch fest verankerter Tanz: Er wird als \u201ekaribisch\u201c bezeichnet, da er auf die musikalischen Traditionen vieler L\u00e4nder Mittel- und S\u00fcdamerikas zur\u00fcckgeht. Doch die stilistischen Elemente, die diesen Tanz heute pr\u00e4gen, stammen aus verschiedenen L\u00e4ndern und Kulturen, allen voran aus den USA. Genau aus diesem Grund ist die Debatte dar\u00fcber, ob man ihn vor den Tendenzen der Vermischung sch\u00fctzen muss, lebhafter und aktueller denn je.<\/p>\n<p>Es gibt diejenigen, die sie wieder zu der Spontaneit\u00e4t und Improvisation ihrer Anf\u00e4nge zur\u00fcckf\u00fchren m\u00f6chten. Andere sind der Meinung, dass sich der kubanische Salsa dadurch zu einem Produkt der karibischen Folklore verkommen w\u00fcrde \u2013 zwar zu einem bedeutenden, aber ohne internationale Ausstrahlung.<\/p>\n<p class=\"margin-top-p1\">&nbsp;<\/p>\n<p>\u00dcber die Bedeutung des Begriffs \u201csalsa\u201d gibt es wenig zu sagen oder zu erfinden. Im Spanischen hat dieser Begriff, der weiblich ist, dieselbe kulinarische Bedeutung wie in unserer Sprache: eine Mischung. Manche sagen, es sei legitim, ihn mit dem Begriff \u201escharf\u201c in Verbindung zu bringen, gerade im Sinne des Geistes des Tanzes selbst, der einzigartig bleiben will.<\/p>\n<p>Es stellt die explosivste Mischung dar, die man aus den vielen bedeutenden lateinamerikanischen und karibischen Elementen in Bezug auf Musik und Tanzformen schaffen k\u00f6nnte. Daher lassen sich das Wort und das Konzept nur mit der Konnotation einer Kombination starker Zutaten in Verbindung bringen, deren Geschmack einen bleibenden Eindruck hinterl\u00e4sst.<\/p>\n<p class=\"margin-top-p1\">&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ruedaloca.it\/wp-content\/uploads\/2025\/09\/lsc_historia_salsa-2x.jpg\" \/><\/p>\n<p class=\"margin-top-p1\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Su luogo e data di origine non ci sono dubbi: la salsa \u00e8 nata a Cuba agli inizi del 1900. Deriva dal Son, ma recepisce elementi importanti da altri balli, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-page-ruedaloca.php","meta":{"footnotes":""},"class_list":["post-1959","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/pages\/1959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/comments?post=1959"}],"version-history":[{"count":27,"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/pages\/1959\/revisions"}],"predecessor-version":[{"id":2025,"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/pages\/1959\/revisions\/2025"}],"wp:attachment":[{"href":"https:\/\/www.ruedaloca.it\/de\/wp-json\/wp\/v2\/media?parent=1959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}