{"id":1951,"date":"2025-09-04T17:59:56","date_gmt":"2025-09-04T15:59:56","guid":{"rendered":"https:\/\/ruedaloca-devel.italix.org\/?page_id=1951"},"modified":"2025-09-04T18:57:31","modified_gmt":"2025-09-04T16:57:31","slug":"metodo-didattico","status":"publish","type":"page","link":"https:\/\/www.ruedaloca.it\/it\/metodo-didattico\/","title":{"rendered":"Il metodo didattico"},"content":{"rendered":"<div>\n<p>Il programma dei corsi prevede <em>7 livelli <\/em>di apprendimento:<\/p>\n<p><em> base 1 &#8211; base 2 &#8211; base 3 &#8211; interm. 1 &#8211; interm. 2 &#8211; avanz.1 &#8211; avanz.2<\/em><\/p>\n<p>Le lezioni sono suddivise in trimestri da <em>10 lezioni <\/em>della durata di un&#8217;ora la quale sar\u00e0 dedicata principalmente all&#8217;insegnamento della salsa cubana o della rueda de casino ( nei corsi interm \/ avanz).<\/p>\n<p>I corsi si avvalgono di un metodo didattico che tiene conto delle differenze individuali in fase di apprendimento con l&#8217;intento di portare gli allievi ad esercitarsi in coppia fin dalle prime lezioni, favorendone le caratteristiche espressive personali.<\/p>\n<p>Ripassata e assimilata la \u201c<em>figura<\/em>\u201d della lezione precedente gli insegnanti ne mostrano una nuova. Poi tutti eseguono molte volte i pezzi che compongono la nuova figura, dapprima singolarmente per poi riaggregarli progressivamente fino a ricomporre la stessa, cambiando anche le coppie per assimilarla meglio.<\/p>\n<p>Grazie a tale didattica ogni allievo al termine del corso avr\u00e0 acquisito la padronanza di <u>tutte le &#8220;figure&#8221;<\/u> insegnate al corso, senza dimenticarne alcuna.<\/p>\n<ul>\n<li><em>Possibilit\u00e0 di integrare i corsi con delle LEZIONI PRIVATE (anche di Domenica)<\/em><\/li>\n<li><em>I corsi sono suddivisi in 7 LIVELLI<\/em><\/li>\n<li><em>I singoli corsi sono costituiti da 10 LEZIONI.<\/em><\/li>\n<li><em>Non occorre iscriversi in coppia.<\/em><\/li>\n<li><em>Se ci si inserisce in un corso gi\u00e0 avviato si ha diritto ugualmente alle 10 lezioni che verranno conteggiate dalla data dell&#8217;iscrizione.<\/em><\/li>\n<\/ul>\n\n<p>Grazie all&#8217;esperienza accumulata nei molti anni di lavoro sul territorio e nei locali latinoamericani, il programma e la metodologia di insegnamento sono stati perfezionati per favorire un rapido e mirato apprendimento delle tecniche fondamentali. A tale scopo sono state selezionate le &#8220;figure&#8221; da insegnare ai corsi in modo da ottimizzarne da subito la loro applicabilit\u00e0 nelle serate da ballo.<\/p>\n<p>La scuola di ballo Rueda Loca propone agli allievi sin dalle prime lezioni il proseguimento, dopo i corsi, nei migliori locali latino americani di Padova che propongono l&#8217;ingresso agevolato con riduzione ai nostri allievi.<\/p>\n<p><strong>La salsa,<\/strong><em> come ogni ballo a coppie, \u00e8 una combinazione di movimenti corporei e di coreografie che si realizza concretamente attraverso un comportamento in un ambiente sociale. Il ballo \u00e8 una maniera di comunicare, \u00e8 un modo intelligente e interessante con il quale esprimersi, \u00e8 connesso fondamentalmente con l\u2019agire umano e quindi implica non solo abilit\u00e0 fisiche, ma anche relazionali.<\/em><\/p>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il programma dei corsi prevede 7 livelli di apprendimento: base 1 &#8211; base 2 &#8211; base 3 &#8211; interm. 1 &#8211; interm. 2 &#8211; avanz.1 &#8211; avanz.2 Le lezioni sono [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-page-ruedaloca.php","meta":{"footnotes":""},"class_list":["post-1951","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/pages\/1951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/comments?post=1951"}],"version-history":[{"count":10,"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/pages\/1951\/revisions"}],"predecessor-version":[{"id":1985,"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/pages\/1951\/revisions\/1985"}],"wp:attachment":[{"href":"https:\/\/www.ruedaloca.it\/it\/wp-json\/wp\/v2\/media?parent=1951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}